{"id":1324,"date":"2022-10-05T14:34:07","date_gmt":"2022-10-05T14:34:07","guid":{"rendered":"https:\/\/movimento-sociale-eurasia.org\/?p=1324"},"modified":"2022-11-12T11:26:49","modified_gmt":"2022-11-12T11:26:49","slug":"lalleanza-b-r-i-c-s-e-uno-dei-motivi-principali-per-cui-gli-stati-uniti-vogliono-fare-la-guerra-alla-russia-di-marco-rigamonti","status":"publish","type":"post","link":"https:\/\/movimento-sociale-eurasia.org\/index.php\/2022\/10\/05\/lalleanza-b-r-i-c-s-e-uno-dei-motivi-principali-per-cui-gli-stati-uniti-vogliono-fare-la-guerra-alla-russia-di-marco-rigamonti\/","title":{"rendered":"L&#8217;Alleanza B.R.I.C.S. \u00e8 uno dei motivi principali per cui gli Stati Uniti vogliono fare la guerra alla Russia &#8211; Di Marco Rigamonti"},"content":{"rendered":"\n<p>La guerra in Ucraina, che \u00e8 palesemente una guerra per procura, che la N.A.T.O. combatte per conto degli Stati Uniti, \u00e8 un conflitto che si combatte su diversi fronti, compreso quello finanziario e delle risorse, al pari se non pi\u00f9 del convenzionale campo di battaglia.<\/p>\n\n\n\n<p>In tale ottica, dobbiamo tener presente che i B.R.I.C.S. stanno per detronizzare gli Stati Uniti ed il loro Dollaro, attraverso nuovi accordi e soprattutto a mezzo degli strumenti che hanno attualmente a loro disposizione e che gli Stati Uniti non possono pi\u00f9 contrastare, se non militarmente, dunque in maniera indiretta.<\/p>\n\n\n\n<p>Pertanto, non ci possiamo limitare ad osservare cosa succede nella battaglia su suolo ucraino, ma dobbiamo ampliare la nostra prospettiva, includendo tutti gli ambiti e situazioni in cui questa guerra viene combattuta ed uno di questi ambiti sono le elezioni in Brasile, che hanno un ruolo molto incisivo in tutto questo, perch\u00e9 gli States stanno combattendo la loro guerra contro i B.R.I.C.S. anche l\u00ec e non solo in Ucraina sfidando la Russia. \u00c8 Lula l\u2019uomo eletto a maggiordomo istituzionale per difendere gli interessi degli Stati Uniti infiltrando il Brasile, nella speranza che inverta la saggia rotta di alleanza coi Paesi dall\u2019economia emergente e che assoggetti cos\u00ec il Brasile ai voleri di Washington.<\/p>\n\n\n\n<p>Se Lula vincer\u00e0, il Brasile far\u00e0 certamente diversi passi indietro dal coordinamento B.R.I.C.S. , i quali attualmente, stanno mettendo a punto delle strategie per detronizzare il Dollaro, usando le proprie valute, che, a differenza del Dollaro, sono di fatto solvibili, perch\u00e9 sostenute dalle risorse e dall\u2019industria. Il Dollaro chiaramente non pu\u00f2 affrontare questa sfida in maniera diretta, attraverso economia, industria e finanza, perch\u00e9 ha esportato troppo della propria industria e soprattutto non ha pi\u00f9 le risorse per garantire ai partner-colonie di mantenere la loro; questa convergenza di fattori, determina perch\u00e9 gli Stati Uniti non abbiano pi\u00f9 una moneta solvibile in tal senso, per non dire che \u00e8 ad un passo dal collassare e questo \u00e8 un altro motivo per cui Washington non vorr\u00e0 fermarsi nella sua guerra contro l\u2019Oriente, se non la fermiamo noi, abbandonando l\u2019Alleanza Atlantica, dunque la N.A.T.O.<\/p>\n\n\n\n<p>Essenzialmente, gli Stati Uniti hanno fatto il proverbiale passo pi\u00f9 lungo della gamba o gli altrimenti detti, conti senza l\u2019oste, come si suol dire. L\u2019espansionismo atlantico, ha incamerato alleati che non poteva permettersi, in una prospettiva di guerra all\u2019Oriente, perch\u00e9 non dobbiamo dimenticarci che la Cina \u00e8 anch\u2019essa coinvolta in gravissime tensioni, che sono quantomeno da plausibile vigilia di guerra.<\/p>\n\n\n\n<p>Per tutte queste ragioni, ci appare quanto sia improbabile un passo indietro da parte degli Stati Uniti, non essendo la vera radice della questione, morale o diplomatica, ma bens\u00ec economica e finanziaria e a guidare le scelte politiche americane, non \u00e8 certo il Governo statunitense in s\u00e9, che \u00e8 solo un Governo fantoccio, ma quell\u2019establishment che controlla e detiene i pi\u00f9 grandi fondi d\u2019investimento, che sono un ristrettissimo gruppo di biechi personaggi, che preferiscono giustamente stare nell\u2019ombra quando devono muovere certi fili, che vengono tirati solo in funzione dei loro interessi personali, senza scrupoli nei riguardi della popolazione, di cui i governi da loro infiltrati, dovrebbe proteggere e curare l\u2019interesse. Purtroppo, fino a quando la politica sar\u00e0 infiltrata dall\u2019alta finanza, l\u2019interesse pubblico sar\u00e0 sempre drammaticamente subalterno alla prima, e se gli interessi privati di questi individui, richiederanno guerre, queste verranno scatenate con o senza il consenso del popolo, indifferentemente dai rischi che questo comporter\u00e0 per la societ\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La guerra in Ucraina, che \u00e8 palesemente una guerra per procura, che la N.A.T.O. combatte per conto degli Stati Uniti, \u00e8 un conflitto che si combatte su diversi fronti, compreso quello finanziario e delle risorse, al pari se non pi\u00f9 del convenzionale campo di battaglia. In tale ottica, dobbiamo tener presente che i B.R.I.C.S. stanno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":""},"categories":[83,15,20],"tags":[96,95,65],"class_list":["post-1324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-approfondimenti","category-articoli","category-attualita-politica","tag-guerra-contro-la-russsia","tag-guerra-in-ucraina","tag-marco-rigamonti"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/posts\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":1,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/posts\/1324\/revisions"}],"predecessor-version":[{"id":1326,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/posts\/1324\/revisions\/1326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/media\/1325"}],"wp:attachment":[{"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/media?parent=1324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/categories?post=1324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/movimento-sociale-eurasia.org\/index.php\/wp-json\/wp\/v2\/tags?post=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}